{"id":77460,"date":"2015-02-19T16:00:15","date_gmt":"2015-02-19T07:00:15","guid":{"rendered":"https:\/\/www.nakisurf.com\/blog\/showroom\/?p=77460"},"modified":"2015-04-16T12:52:13","modified_gmt":"2015-04-16T03:52:13","slug":"canvas%e3%80%8eracecar-%e3%83%ac%e3%83%bc%e3%82%b9%e3%82%ab%e3%83%bc%e3%80%8f52-x-20-12-x-2-12_%e9%9d%a2%e3%81%a8%e7%b7%9a%e3%82%92%e6%84%8f%e8%ad%98%e3%81%97%e3%81%a6%e7%88%86%e7%99%ba","status":"publish","type":"post","link":"https:\/\/www.nakisurf.com\/blog\/showroom\/archives\/77460","title":{"rendered":"CANVAS\u300eRACECAR (\u30ec\u30fc\u30b9\u30ab\u30fc)\u300f5&#8217;2&#8243; x 20-1\/2&#8243; x 2-1\/2&#8243;_\u9762\u3068\u7dda\u3092\u610f\u8b58\u3057\u3066\u7206\u767a\u7684\u30c9\u30e9\u30a4\u30d6\u6027\u80fd\u3092\u751f\u307f\u51fa\u3059"},"content":{"rendered":"<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219hagi.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219hagi-700x556.jpg\" alt=\"srblog20150219hagi\" width=\"700\" height=\"556\" class=\"alignnone size-large wp-image-77461\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219hagi.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219hagi-400x318.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>\u30b9\u30bf\u30c3\u30d5\u306f\u304e\u3046\u3060<\/strong><br \/>\n<strong>\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc<\/strong><br \/>\n<strong> \u8eab\u9577\uff1a169cm<\/strong><br \/>\n<strong> \u4f53\u91cd\uff1a60kg<\/strong><br \/>\n<strong> \u30b3\u30e1\u30f3\u30c8\uff1aRACECAR\u3092\u82e5\u5e72\u306e\u30aa\u30fc\u30d0\u30fc\u30d5\u30ed\u30fc\u30c8\u6c17\u5473\u3067\u30aa\u30fc\u30c0\u30fc\u3002<\/strong><br \/>\n<strong> \u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc<\/strong><\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/brand\/canvas\/racecar\/\" target=\"_blank\">https:\/\/www.nakisurf.com\/brand\/canvas\/racecar\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 140%;\"><strong>\u3010CANVAS\u300eRACECAE (\u30ec\u30fc\u30b9\u30ab\u30fc)\u300f\u30a4\u30f3\u30d7\u30ec\u30c3\u30b7\u30e7\u30f3\u3011<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219a.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219a-700x467.jpg\" alt=\"srblog20150219a\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77462\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219a.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219a-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>[\u30c6\u30a4\u30af\u30aa\u30d5]<\/strong><\/p>\n<p>\u7de9\u3044\u6ce2\u3067\u3082\u30b0\u30fc\u30f3\u3068\u8d70\u308a\u51fa\u3057\u307e\u3059\u3002<\/p>\n<p>\u7279\u306b\u539a\u3044\u6ce2\u3067\u306f\u3053\u306e\u4f4d\u7f6e\u304b\u3089\u4f59\u88d5\u3092\u6301\u3063\u3066\u3001<\/p>\n<p>\u6ce2\u304c\u5d29\u308c\u3066\u304f\u308b\u306e\u3092\u5f85\u3066\u308b\u306e\u3067\u30a2\u30c9\u30d0\u30f3\u30c6\u30fc\u30b8\u306b\u306a\u308a\u307e\u3059\u3002<\/p>\n<p>\u77ed\u3044\u30dc\u30fc\u30c9\u306f\u30d1\u30c9\u30eb\u3059\u308b\u4f4d\u7f6e\u3082\u5927\u5207\u306a\u306e\u3067\u3001<\/p>\n<p>\u5c11\u3057\u524d\u5bc4\u308a\u306e\u3001\u5b89\u5b9a\u3057\u3066\u4e00\u756a\u901f\u304f\u9032\u3080\u5834\u6240\u3092\u899a\u3048\u308b\u306e\u304c\u826f\u3044\u3067\u3059\u3002<\/p>\n<p>\u7279\u306b\u5e45\u5e83\u30df\u30cb\u30dc\u30fc\u30c9\u306f\u3001<\/p>\n<p>\u305d\u306e\u4f4d\u7f6e\u611f\u899a\u3092\u30ab\u30e9\u30c0\u3067\u899a\u3048\u308b\u3053\u3068\u3067\u3001<\/p>\n<p>\u30dc\u30fc\u30c9\u304c\u6301\u3064\u30c6\u30a4\u30af\u30aa\u30d5\u306e\u901f\u3055\u3092\u6d3b\u304b\u305b\u308b\u3088\u3046\u306b\u306a\u308a\u307e\u3059\u3002<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219c.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219c-700x467.jpg\" alt=\"srblog20150219c\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77463\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219c.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219c-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>[\u30b0\u30e9\u30a4\u30c9\u611f\u3001\u901f\u3055\u3001\u5b89\u5b9a\u611f]<\/strong><\/p>\n<p>\u30cf\u30a4\u30e9\u30a4\u30f3\u6ed1\u8d70\u3001\u3053\u3053\u304c\u30ec\u30fc\u30b9\u30ab\u30fc\u306e\u9762\u767d\u3044\u5834\u9762\u3002<\/p>\n<p>\u307e\u3055\u306b\u3001\u92ad\u6e6f\u306e\u5e8a\u3067\u77f3\u9e78\u3092\u30b9\u30fc\u30fc\u30c3\u3068\u6ed1\u3089\u305b\u305f\u3088\u3046\u306a\u3001<\/p>\n<p>\u6469\u64e6\u306e\u306a\u3044\u30b9\u30e0\u30fc\u30ba\u306a\u52a0\u901f\u3068\u3044\u3046\u611f\u3058\u3067\u3059\u3002<\/p>\n<p>\u30ef\u30a4\u30c9\u306a\u30c6\u30a4\u30eb\u30a8\u30ea\u30a2\u3001<\/p>\n<p>\u6ce2\u306e\u30d1\u30ef\u30fc\u3092\u5e83\u3044\u9762\u3067\u3046\u3051\u3066\u3044\u308b\u611f\u899a\u3002<\/p>\n<p>\u5b89\u5b9a\u3057\u3066\u52a0\u901f\u3057\u3066\u304f\u308c\u308b\u306e\u3067\u723d\u5feb\u611f\u304c\u30cf\u30f3\u30d1\u3067\u306f\u306a\u3044\u3067\u3059\u3002<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219b.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219b-700x467.jpg\" alt=\"srblog20150219b\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77464\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219b.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219b-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>[\u30bf\u30fc\u30f3\u6027\u80fd]<\/strong><\/p>\n<p>\u6c17\u306b\u306a\u308b\u30bf\u30fc\u30f3\u6027\u80fd\u306f\uff1f<\/p>\n<p>\u30af\u30a4\u30c3\u30af \u30af\u30a4\u30c3\u30af \u30af\u30a4\u30c3\u30af\uff01\uff01<\/p>\n<p>&#8220;\u30af\u30a4\u30c3\u30af\u3060\u304b\u3089\u3053\u305d&#8221;\u306e\u4e57\u308a\u65b9\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n<p>\u305d\u308c\u306f\u300c\u3042\u3048\u3066\u3057\u3063\u304b\u308a\u30ec\u30a4\u30eb\u3092\u610f\u8b58\u3059\u308b\u3068\u3044\u3046\u3053\u3068\u300d\u3002<\/p>\n<p>\u9762\u304b\u3089\u7dda\u3078\u3002<\/p>\n<p>\u30dc\u30c8\u30e0\uff08\u9762\uff09\u304b\u3089\u30ec\u30a4\u30eb\u30e9\u30a4\u30f3\uff08\u7dda\uff09\u3078\u3002<\/p>\n<p>\u3053\u306e\u5207\u308a\u66ff\u3048\u3067\u751f\u307e\u308c\u308b\u7206\u767a\u7684\u306a\u30c9\u30e9\u30a4\u30d6\u611f\u3002<\/p>\n<p>\u3053\u306e\u3088\u3046\u306a\u539a\u3081\u306e\u6ce2\u3067\u3082\u3001<\/p>\n<p>G\u3092\u611f\u3058\u3089\u308c\u308b\u306e\u304cRACECAR\u306e\u826f\u3055\u3067\u3059\u3002<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq1-700x467.jpg\" alt=\"srblog20150219seq1\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77465\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq1.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq1-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq2-700x467.jpg\" alt=\"srblog20150219seq2\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77466\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq2.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq2-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq3.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq3-700x467.jpg\" alt=\"srblog20150219seq3\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77467\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq3.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq3-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq4.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq4-700x467.jpg\" alt=\"srblog20150219seq4\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77468\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq4.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq4-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq5.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq5-700x467.jpg\" alt=\"srblog20150219seq5\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77469\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq5.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq5-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq6.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq6-700x467.jpg\" alt=\"srblog20150219seq6\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77470\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq6.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq6-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq7.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq7-700x467.jpg\" alt=\"srblog20150219seq7\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77471\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq7.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq7-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq8.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq8-700x467.jpg\" alt=\"srblog20150219seq8\" width=\"700\" height=\"467\" class=\"alignnone size-large wp-image-77472\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq8.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/srblog20150219seq8-400x267.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>[\u30b7\u30fc\u30af\u30a8\u30f3\u30b9\u5199\u771f\u3067\u6027\u80fd\u5206\u6790]<\/strong><\/p>\n<p>1\u30b3\u30de\u76ee\u306e\u6ce2\u306e\u30e9\u30a4\u30f3\u3092\u898b\u3066\u3082\u3089\u3046\u3068\u5206\u304b\u308a\u307e\u3059\u304c\u3001<\/p>\n<p>\u30b7\u30f3\u30b0\u30eb\u30b3\u30f3\u30b1\u30a4\u30d6\u3068\u30c4\u30a4\u30f3\u30d5\u30a3\u30f3\u306e\u592a\u3044\u30c8\u30e9\u30c3\u30af\u3002<\/p>\n<p>\u3053\u3053\u304b\u3089\u30dc\u30c8\u30e0\u306b\u304b\u3051\u3066\u306e\u9ad8\u30c9\u30e9\u30a4\u30d6\u611f\u304c\u305f\u307e\u308a\u307e\u305b\u3093\u301c\u3002<\/p>\n<p>\u30c9\u30e9\u30a4\u30d6\u306e\u52b9\u3044\u305f\u30dc\u30c8\u30e0\u30bf\u30fc\u30f3\u304b\u3089\u3001<\/p>\n<p>\u6ce2\u306e\u7de9\u3044\u30bb\u30af\u30b7\u30e7\u30f3\u3067\u5f90\u3005\u306b\u30bf\u30fc\u30f3\u306b\u5165\u308b\u3068\u3001<\/p>\n<p>\u30dc\u30fc\u30c9\u304c\u30af\u30a4\u30c3\u30af\u306b\u53cd\u5fdc\u3057\u3066\u30ad\u30e5\u30c3\u3068\u6ce2\u306e\u30dd\u30b1\u30c3\u30c8\u306b\u5165\u308a\u8fbc\u307f\u307e\u3059\u3002<\/p>\n<p>\u30bf\u30fc\u30f3\u5f8c\u534a\u306f\u30dc\u30fc\u30c9\u306e\u5b89\u5b9a\u611f\u3068\u67d4\u3089\u304b\u3044\u30b3\u30f3\u30c8\u30ed\u30fc\u30eb\u6027\u3067\u3001<\/p>\n<p>\u6b21\u306e\u30bb\u30af\u30b7\u30e7\u30f3\u3078\u3068\u8a98\u5c0e\u3055\u308c\u308b\u3088\u3046\u306b\u9032\u3093\u3067\u3044\u304d\u307e\u3059\u3002<\/p>\n<p>\u4e57\u308a\u8fbc\u3080\u3054\u3068\u306b\u8abf\u5b50\u3088\u3055\u3092\u5897\u3059\u30ec\u30fc\u30b9\u30ab\u30fc\u3002<\/p>\n<p>\u8d85\u540d\u4f5c\u30d0\u30bf\u30fc\u30be\u30fc\u30f3\u3092\u3057\u306e\u3050\u307b\u3069\u306e\u53ef\u80fd\u6027\u3092\u79d8\u3081\u305f\u3001<\/p>\n<p>\u304a\u697d\u3057\u307f\u30de\u30f3\u30e9\u30a4\u30dc\u30fc\u30c9\u3001\u30ec\u30fc\u30b9\u30ab\u30fc\u306b\u5927\u6ce8\u76ee\u3067\u3059\uff01<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 140%;\"><strong>\u3010\u5373\u7d0d\u53ef\u80fd\u306e\u30b9\u30c8\u30c3\u30af\u30dc\u30fc\u30c9\u3011<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/ca_racecar1004_001.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/ca_racecar1004_001-700x700.jpg\" alt=\"ca_racecar1004_001\" width=\"700\" height=\"700\" class=\"alignnone size-large wp-image-77447\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/ca_racecar1004_001.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/ca_racecar1004_001-400x400.jpg 400w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/ca_racecar1004_001-230x230.jpg 230w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/ca_racecar1004_001-80x80.jpg 80w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>RACECAR\u30005&#8217;2&#8243; x 20 1\/2&#8243; x 2 5\/16&#8243;\u3000\u30b7\u30e2\u30f3\u30ba\u30b9\u30af\u30a8\u30a2\u3000\u30c4\u30a4\u30f3\u30aa\u30f3\u30d5\u30a3\u30f3\u3000CA754<\/strong><\/p>\n<p><a href=\"https:\/\/www.nakisurfshop.com\/SHOP\/CA754.html\" target=\"_blank\">https:\/\/www.nakisurfshop.com\/SHOP\/CA754.html<\/a><\/p>\n<p>.<\/p>\n<p><a href=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/CA778-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/CA778-1-700x700.jpg\" alt=\"CA778-1\" width=\"700\" height=\"700\" class=\"alignnone size-large wp-image-77449\" srcset=\"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/CA778-1.jpg 700w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/CA778-1-400x400.jpg 400w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/CA778-1-230x230.jpg 230w, https:\/\/www.nakisurf.com\/blog\/showroom\/wp-content\/uploads\/2015\/02\/CA778-1-80x80.jpg 80w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>RACECAR\u30005&#8217;1&#8243; x 20 1\/2&#8243; x 2 5\/16&#8243;\u3000\u30b7\u30e2\u30f3\u30ba\u30b9\u30af\u30a8\u30a2\u3000\u30c4\u30a4\u30f3\u30aa\u30f3\u30d5\u30a3\u30f3\u3000CA778<\/strong><\/p>\n<p><a href=\"https:\/\/www.nakisurfshop.com\/SHOP\/CA778.html\" target=\"_blank\">https:\/\/www.nakisurfshop.com\/SHOP\/CA778.html<\/a><\/p>\n<p>.<\/p>\n<p>\uff08\u306f\u304e\uff09<\/p>\n","protected":false},"excerpt":{"rendered":"\u30b9\u30bf\u30c3\u30d5\u306f\u304e\u3046\u3060 \u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc \u8eab\u9577\uff1a169cm \u4f53\u91cd\uff1a60kg \u30b3\u30e1\u30f3\u30c8\uff1aRACECAR\u3092\u82e5\u5e72\u306e\u30aa\u30fc\u30d0\u30fc\u30d5\u30ed\u30fc\u30c8\u6c17\u5473\u3067\u30aa\u30fc\u30c0\u30fc\u3002 \u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc\u30fc https:\/\/www.nakisurf.com\/bran [&hellip;]","protected":false},"author":11,"featured_media":77471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[172,250,252],"class_list":["post-77460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impression","tag-canvas","tag-racecar","tag-252"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/posts\/77460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/comments?post=77460"}],"version-history":[{"count":0,"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/posts\/77460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/media\/77471"}],"wp:attachment":[{"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/media?parent=77460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/categories?post=77460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nakisurf.com\/blog\/showroom\/wp-json\/wp\/v2\/tags?post=77460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}